{"id":2417,"date":"2020-10-21T10:24:34","date_gmt":"2020-10-21T08:24:34","guid":{"rendered":"https:\/\/www.cpt-ch.ch\/?page_id=2417"},"modified":"2026-02-09T07:50:27","modified_gmt":"2026-02-09T06:50:27","slug":"membri","status":"publish","type":"page","link":"https:\/\/www.cpt-ch.ch\/it\/membri\/","title":{"rendered":"Membri"},"content":{"rendered":"Devi essere connesso per visualizzare questo contenuto.","protected":false},"excerpt":{"rendered":"Devi essere connesso per visualizzare questo contenuto.","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"page-member.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2417","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Membri - Herdenschutzhunde Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cpt-ch.ch\/it\/membri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Membri - Herdenschutzhunde Schweiz\" \/>\n<meta property=\"og:description\" content=\"Questo contenuto \u00e8 riservato ai membri del sito. Se sei gi\u00e0 registrato, accedi. I nuovi utenti possono registrarsi qui sotto.Accesso per utenti iscrittiNome utente o emailPassword&nbsp;Ricordami&nbsp;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cpt-ch.ch\/it\/membri\/\" \/>\n<meta property=\"og:site_name\" content=\"Herdenschutzhunde Schweiz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T06:50:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/membri\\\/\",\"url\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/membri\\\/\",\"name\":\"Membri - Herdenschutzhunde Schweiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/#website\"},\"datePublished\":\"2020-10-21T08:24:34+00:00\",\"dateModified\":\"2026-02-09T06:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/membri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/membri\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/membri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Membri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/\",\"name\":\"Herdenschutzhunde Schweiz\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cpt-ch.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Membri - Herdenschutzhunde Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cpt-ch.ch\/it\/membri\/","og_locale":"it_IT","og_type":"article","og_title":"Membri - Herdenschutzhunde Schweiz","og_description":"Questo contenuto \u00e8 riservato ai membri del sito. Se sei gi\u00e0 registrato, accedi. I nuovi utenti possono registrarsi qui sotto.Accesso per utenti iscrittiNome utente o emailPassword&nbsp;Ricordami&nbsp;&nbsp;","og_url":"https:\/\/www.cpt-ch.ch\/it\/membri\/","og_site_name":"Herdenschutzhunde Schweiz","article_modified_time":"2026-02-09T06:50:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cpt-ch.ch\/it\/membri\/","url":"https:\/\/www.cpt-ch.ch\/it\/membri\/","name":"Membri - Herdenschutzhunde Schweiz","isPartOf":{"@id":"https:\/\/www.cpt-ch.ch\/it\/#website"},"datePublished":"2020-10-21T08:24:34+00:00","dateModified":"2026-02-09T06:50:27+00:00","breadcrumb":{"@id":"https:\/\/www.cpt-ch.ch\/it\/membri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cpt-ch.ch\/it\/membri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cpt-ch.ch\/it\/membri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cpt-ch.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Membri"}]},{"@type":"WebSite","@id":"https:\/\/www.cpt-ch.ch\/it\/#website","url":"https:\/\/www.cpt-ch.ch\/it\/","name":"Herdenschutzhunde Schweiz","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cpt-ch.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/pages\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/comments?post=2417"}],"version-history":[{"count":4,"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/pages\/2417\/revisions"}],"predecessor-version":[{"id":3292,"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/pages\/2417\/revisions\/3292"}],"wp:attachment":[{"href":"https:\/\/www.cpt-ch.ch\/it\/wp-json\/wp\/v2\/media?parent=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}